{"id":495,"date":"2023-04-26T12:08:17","date_gmt":"2023-04-26T17:08:17","guid":{"rendered":"https:\/\/wowboxgifts.com\/?post_type=product&#038;p=495"},"modified":"2025-03-25T13:57:22","modified_gmt":"2025-03-25T18:57:22","slug":"talla-s","status":"publish","type":"product","link":"https:\/\/wowboxgifts.com\/en\/product\/talla-s\/","title":{"rendered":"Size S"},"content":{"rendered":"<p>S\u00e1ndwich de jam\u00f3n, queso y vegetales o waffles con fresas y miel, Ensalada de frutas , Jugo de naranja, Milo, <strong>Mini ponquecito con vela<\/strong>, Corazones de hojaldre, Caja de cart\u00f3n del color que m\u00e1s te guste, Lazos decorativos y 2 globos latex, <strong>Tarjeta personalizada y mini foto<\/strong> y Cubiertos y pitillo BIO.<\/p>","protected":false},"excerpt":{"rendered":"<p>S\u00e1ndwich de jam\u00f3n, queso y vegetales o waffles con fresas y miel, Ensalada de frutas , Jugo de naranja, Milo, Mini ponquecito con vela, Corazones de hojaldre, Caja de cart\u00f3n del color que m\u00e1s te guste, Lazos decorativos y 2 globos latex, Tarjeta personalizada y mini foto y Cubiertos y pitillo BIO.<\/p>","protected":false},"featured_media":3488,"template":"","meta":[],"product_brand":[],"product_cat":[24],"product_tag":[],"class_list":{"0":"post-495","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-desayunos","8":"first","9":"instock","10":"shipping-taxable","11":"purchasable","12":"product-type-variable"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.8 (Yoast SEO v22.8) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Talla S - wowboxgifts.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wowboxgifts.com\/en\/product\/talla-s\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Talla S\" \/>\n<meta property=\"og:description\" content=\"S\u00e1ndwich de jam\u00f3n, queso y vegetales o waffles con fresas y miel, Ensalada de frutas , Jugo de naranja, Milo, Mini ponquecito con vela, Corazones de hojaldre, Caja de cart\u00f3n del color que m\u00e1s te guste, Lazos decorativos y 2 globos latex, Tarjeta personalizada y mini foto y Cubiertos y pitillo BIO.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wowboxgifts.com\/en\/product\/talla-s\/\" \/>\n<meta property=\"og:site_name\" content=\"wowboxgifts.com\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-25T18:57:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/wowboxgifts.com\/wp-content\/uploads\/2023\/04\/talla_s_2025_2_6.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/wowboxgifts.com\/en\/product\/talla-s\/\",\"url\":\"https:\/\/wowboxgifts.com\/en\/product\/talla-s\/\",\"name\":\"Talla S - wowboxgifts.com\",\"isPartOf\":{\"@id\":\"https:\/\/wowboxgifts.com\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/wowboxgifts.com\/en\/product\/talla-s\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/wowboxgifts.com\/en\/product\/talla-s\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/wowboxgifts.com\/wp-content\/uploads\/2023\/04\/talla_s_2025_2_6.jpg\",\"datePublished\":\"2023-04-26T17:08:17+00:00\",\"dateModified\":\"2025-03-25T18:57:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/wowboxgifts.com\/en\/product\/talla-s\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/wowboxgifts.com\/en\/product\/talla-s\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/wowboxgifts.com\/en\/product\/talla-s\/#primaryimage\",\"url\":\"https:\/\/wowboxgifts.com\/wp-content\/uploads\/2023\/04\/talla_s_2025_2_6.jpg\",\"contentUrl\":\"https:\/\/wowboxgifts.com\/wp-content\/uploads\/2023\/04\/talla_s_2025_2_6.jpg\",\"width\":750,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/wowboxgifts.com\/en\/product\/talla-s\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/wowboxgifts.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Products\",\"item\":\"https:\/\/wowboxgifts.com\/en\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Talla S\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/wowboxgifts.com\/en\/#website\",\"url\":\"https:\/\/wowboxgifts.com\/en\/\",\"name\":\"wowboxgifts.com\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/wowboxgifts.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/wowboxgifts.com\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/wowboxgifts.com\/en\/#organization\",\"name\":\"wowboxgifts.com\",\"url\":\"https:\/\/wowboxgifts.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/wowboxgifts.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/wowboxgifts.com\/wp-content\/uploads\/2025\/01\/wowbox-logo.png\",\"contentUrl\":\"https:\/\/wowboxgifts.com\/wp-content\/uploads\/2025\/01\/wowbox-logo.png\",\"width\":850,\"height\":757,\"caption\":\"wowboxgifts.com\"},\"image\":{\"@id\":\"https:\/\/wowboxgifts.com\/en\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Talla S - wowboxgifts.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wowboxgifts.com\/en\/product\/talla-s\/","og_locale":"en_US","og_type":"article","og_title":"Talla S","og_description":"S\u00e1ndwich de jam\u00f3n, queso y vegetales o waffles con fresas y miel, Ensalada de frutas , Jugo de naranja, Milo, Mini ponquecito con vela, Corazones de hojaldre, Caja de cart\u00f3n del color que m\u00e1s te guste, Lazos decorativos y 2 globos latex, Tarjeta personalizada y mini foto y Cubiertos y pitillo BIO.","og_url":"https:\/\/wowboxgifts.com\/en\/product\/talla-s\/","og_site_name":"wowboxgifts.com","article_modified_time":"2025-03-25T18:57:22+00:00","og_image":[{"width":750,"height":1000,"url":"https:\/\/wowboxgifts.com\/wp-content\/uploads\/2023\/04\/talla_s_2025_2_6.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/wowboxgifts.com\/en\/product\/talla-s\/","url":"https:\/\/wowboxgifts.com\/en\/product\/talla-s\/","name":"Talla S - wowboxgifts.com","isPartOf":{"@id":"https:\/\/wowboxgifts.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/wowboxgifts.com\/en\/product\/talla-s\/#primaryimage"},"image":{"@id":"https:\/\/wowboxgifts.com\/en\/product\/talla-s\/#primaryimage"},"thumbnailUrl":"https:\/\/wowboxgifts.com\/wp-content\/uploads\/2023\/04\/talla_s_2025_2_6.jpg","datePublished":"2023-04-26T17:08:17+00:00","dateModified":"2025-03-25T18:57:22+00:00","breadcrumb":{"@id":"https:\/\/wowboxgifts.com\/en\/product\/talla-s\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wowboxgifts.com\/en\/product\/talla-s\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/wowboxgifts.com\/en\/product\/talla-s\/#primaryimage","url":"https:\/\/wowboxgifts.com\/wp-content\/uploads\/2023\/04\/talla_s_2025_2_6.jpg","contentUrl":"https:\/\/wowboxgifts.com\/wp-content\/uploads\/2023\/04\/talla_s_2025_2_6.jpg","width":750,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/wowboxgifts.com\/en\/product\/talla-s\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/wowboxgifts.com\/"},{"@type":"ListItem","position":2,"name":"Products","item":"https:\/\/wowboxgifts.com\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"Talla S"}]},{"@type":"WebSite","@id":"https:\/\/wowboxgifts.com\/en\/#website","url":"https:\/\/wowboxgifts.com\/en\/","name":"wowboxgifts.com","description":"","publisher":{"@id":"https:\/\/wowboxgifts.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wowboxgifts.com\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/wowboxgifts.com\/en\/#organization","name":"wowboxgifts.com","url":"https:\/\/wowboxgifts.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/wowboxgifts.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/wowboxgifts.com\/wp-content\/uploads\/2025\/01\/wowbox-logo.png","contentUrl":"https:\/\/wowboxgifts.com\/wp-content\/uploads\/2025\/01\/wowbox-logo.png","width":850,"height":757,"caption":"wowboxgifts.com"},"image":{"@id":"https:\/\/wowboxgifts.com\/en\/#\/schema\/logo\/image\/"}}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/wowboxgifts.com\/en\/wp-json\/wp\/v2\/product\/495","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wowboxgifts.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/wowboxgifts.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wowboxgifts.com\/en\/wp-json\/wp\/v2\/media\/3488"}],"wp:attachment":[{"href":"https:\/\/wowboxgifts.com\/en\/wp-json\/wp\/v2\/media?parent=495"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/wowboxgifts.com\/en\/wp-json\/wp\/v2\/product_brand?post=495"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/wowboxgifts.com\/en\/wp-json\/wp\/v2\/product_cat?post=495"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/wowboxgifts.com\/en\/wp-json\/wp\/v2\/product_tag?post=495"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}